{"id":64982,"date":"2022-03-17T14:39:48","date_gmt":"2022-03-17T14:39:48","guid":{"rendered":"https:\/\/www.mobles114.com\/professional-area\/downloads\/"},"modified":"2024-03-14T11:45:54","modified_gmt":"2024-03-14T11:45:54","slug":"downloads","status":"publish","type":"page","link":"https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/","title":{"rendered":"Downloads"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":56330,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"page-downloads.php","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-64982","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Downloads de tipos de Mobiliario Contract para tu negocio | Mobles 114<\/title>\n<meta name=\"description\" content=\"Mobles 114 proporciona informaci\u00f3n de productos Mobiliario Contract para tu negocio: fichas t\u00e9cnicas, im\u00e1genes y m\u00e1s. Contacte profesionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Downloads de tipos de Mobiliario Contract para tu negocio | Mobles 114\" \/>\n<meta property=\"og:description\" content=\"Mobles 114 proporciona informaci\u00f3n de productos Mobiliario Contract para tu negocio: fichas t\u00e9cnicas, im\u00e1genes y m\u00e1s. Contacte profesionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobles 114\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-14T11:45:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/professional-area\\\/downloads\\\/\",\"url\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/professional-area\\\/downloads\\\/\",\"name\":\"Downloads de tipos de Mobiliario Contract para tu negocio | Mobles 114\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/#website\"},\"datePublished\":\"2022-03-17T14:39:48+00:00\",\"dateModified\":\"2024-03-14T11:45:54+00:00\",\"description\":\"Mobles 114 proporciona informaci\u00f3n de productos Mobiliario Contract para tu negocio: fichas t\u00e9cnicas, im\u00e1genes y m\u00e1s. Contacte profesionales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/professional-area\\\/downloads\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mobles114.com\\\/en\\\/professional-area\\\/downloads\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/professional-area\\\/downloads\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/home-2026\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professionals\",\"item\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/professional-area\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Downloads\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/\",\"name\":\"Mobles 114\",\"description\":\"Mobiliario de dise\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mobles114.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Downloads de tipos de Mobiliario Contract para tu negocio | Mobles 114","description":"Mobles 114 proporciona informaci\u00f3n de productos Mobiliario Contract para tu negocio: fichas t\u00e9cnicas, im\u00e1genes y m\u00e1s. Contacte profesionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/","og_locale":"en_US","og_type":"article","og_title":"Downloads de tipos de Mobiliario Contract para tu negocio | Mobles 114","og_description":"Mobles 114 proporciona informaci\u00f3n de productos Mobiliario Contract para tu negocio: fichas t\u00e9cnicas, im\u00e1genes y m\u00e1s. Contacte profesionales.","og_url":"https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/","og_site_name":"Mobles 114","article_modified_time":"2024-03-14T11:45:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/","url":"https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/","name":"Downloads de tipos de Mobiliario Contract para tu negocio | Mobles 114","isPartOf":{"@id":"https:\/\/www.mobles114.com\/en\/#website"},"datePublished":"2022-03-17T14:39:48+00:00","dateModified":"2024-03-14T11:45:54+00:00","description":"Mobles 114 proporciona informaci\u00f3n de productos Mobiliario Contract para tu negocio: fichas t\u00e9cnicas, im\u00e1genes y m\u00e1s. Contacte profesionales.","breadcrumb":{"@id":"https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mobles114.com\/en\/professional-area\/downloads\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mobles114.com\/en\/home-2026\/"},{"@type":"ListItem","position":2,"name":"Professionals","item":"https:\/\/www.mobles114.com\/en\/professional-area\/"},{"@type":"ListItem","position":3,"name":"Downloads"}]},{"@type":"WebSite","@id":"https:\/\/www.mobles114.com\/en\/#website","url":"https:\/\/www.mobles114.com\/en\/","name":"Mobles 114","description":"Mobiliario de dise\u00f1o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mobles114.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.mobles114.com\/en\/wp-json\/wp\/v2\/pages\/64982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mobles114.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mobles114.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mobles114.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mobles114.com\/en\/wp-json\/wp\/v2\/comments?post=64982"}],"version-history":[{"count":2,"href":"https:\/\/www.mobles114.com\/en\/wp-json\/wp\/v2\/pages\/64982\/revisions"}],"predecessor-version":[{"id":64991,"href":"https:\/\/www.mobles114.com\/en\/wp-json\/wp\/v2\/pages\/64982\/revisions\/64991"}],"up":[{"embeddable":true,"href":"https:\/\/www.mobles114.com\/en\/wp-json\/wp\/v2\/pages\/56330"}],"wp:attachment":[{"href":"https:\/\/www.mobles114.com\/en\/wp-json\/wp\/v2\/media?parent=64982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}